
{"id":14254,"date":"2018-06-05T18:49:07","date_gmt":"2018-06-05T16:49:07","guid":{"rendered":"http:\/\/www.blogdelaautoescuela.com\/blog\/?p=14254"},"modified":"2019-06-11T13:19:04","modified_gmt":"2019-06-11T11:19:04","slug":"examen-de-directores-de-autoescuela-22-de-noviembre-de-2018","status":"publish","type":"post","link":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/","title":{"rendered":"Examen de Directores de autoescuela: 22 de Noviembre de 2018"},"content":{"rendered":"<p><a href=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/http:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg\"><img data-opt-id=56085413  fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-779 aligncenter\" src=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/http:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg\" alt=\"\" width=\"400\" height=\"200\" srcset=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:400\/h:200\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg 400w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:300\/h:150\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">La <strong>Direcci\u00f3n General de Tr\u00e1fico<\/strong>\u00a0 ha publicado en su p\u00e1gina web el temario recomendado para preparar el examen de director de escuelas particulares de conductores, la fecha del examen y los listados provisionales de admitidos y exclu\u00ed\u00addos.<\/p>\n<p>La fecha del examen ser\u00e1 el <strong>22 de noviembre de 2018<\/strong>, a las 16:30 horas en todas las comunidades, excepto en la Comunidad Aut\u00f3noma Canaria, en la que empezar\u00e1 a las 15:30 horas.<\/p>\n<p>Pod\u00e9is consultar los listados en estos enlaces:<\/p>\n<ul>\n<li><a title=\"Acceder a Resoluci\u00f3n relaci\u00f3n provisional de aspirantes admitidos y excluidos prueba selectiva.\" href=\"http:\/\/www.dgt.es\/Galerias\/seguridad-vial\/formacion-vial\/cursos-para-profesores-y-directores-de-autoescuelas\/Directores-2017\/Resolucion-relacion-provisional-de-aspirantes-admitidos-y-excluidos-prueba-selectiva.pdf\">Resoluci\u00f3n relaci\u00f3n provisional de aspirantes admitidos y excluidos prueba selectiva.<\/a><\/li>\n<li><a title=\"Acceder a Relaci\u00f3n provisional de aspirantes excluidos.\" href=\"http:\/\/www.dgt.es\/Galerias\/seguridad-vial\/formacion-vial\/cursos-para-profesores-y-directores-de-autoescuelas\/Directores-2017\/Relacion-provisional-de-aspirantes-excluidos.pdf\">Relaci\u00f3n provisional de aspirantes excluidos.<\/a><\/li>\n<li><a title=\"Acceder a Relaci\u00f3n provisional de aspirantes admitidos.\" href=\"http:\/\/www.dgt.es\/Galerias\/seguridad-vial\/formacion-vial\/cursos-para-profesores-y-directores-de-autoescuelas\/Directores-2017\/Relacion-provisional-de-aspirantes-admitidos.pdf\">Relaci\u00f3n provisional de aspirantes admitidos.<\/a><\/li>\n<li><a title=\"Acceder a Temario Prueba selectiva.\" href=\"http:\/\/www.dgt.es\/Galerias\/seguridad-vial\/formacion-vial\/cursos-para-profesores-y-directores-de-autoescuelas\/Directores-2017\/Temario-prueba-selectiva..pdf\">Temario Prueba selectiva.<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>MATERIAL DE ESTUDIO<\/strong><\/p>\n<p>Os recomendamos los test y manuales de Arisoft. Visita su <a href=\"http:\/\/www.arisoft.es\/tienda\/16-director-de-autoescuela\">tienda online.<\/a><\/p>\n<h5><a class=\"product-name\" title=\"Pack ahorro - Director de autoescuela\" href=\"http:\/\/www.arisoft.es\/tienda\/director-de-autoescuela\/23-pack-director-de-autoescuela\" target=\"_blank\" rel=\"noopener\"><span class=\"grid-name\">PACK AHORRO &#8211; DIRECTOR DE AUTOESCUELA<\/span><\/a><\/h5>\n<h5><a class=\"product-name\" title=\"Test - Director de autoescuela\" href=\"http:\/\/www.arisoft.es\/tienda\/director-de-autoescuela\/44-test-director-de-autoescuela\" target=\"_blank\" rel=\"noopener\"><span class=\"grid-name\">TEST &#8211; DIRECTOR DE AUTOESCUELA<\/span><\/a><\/h5>\n<h5><a class=\"product-name\" title=\"Pack ahorro Manuales - Director de autoescuela\" href=\"http:\/\/www.arisoft.es\/tienda\/home\/63-manuales-director-de-autoescuela\" target=\"_blank\" rel=\"noopener\"><span class=\"grid-name\">PACK AHORRO MANUALES &#8211; DIRECTOR DE AUTOESCUELA<\/span><\/a><\/h5>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Tr\u00e1fico\u00a0 ha publicado en su p\u00e1gina web el temario recomendado para preparar el examen de director de escuelas particulares de conductores, la fecha del examen y los listados provisionales de admitidos y exclu\u00ed\u00addos. La fecha del examen ser\u00e1 el 22 de noviembre de 2018, a las 16:30 horas en todas las [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":779,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-14254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-vial"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Examen de Directores de autoescuela: 22 de Noviembre de 2018<\/title>\n<meta name=\"description\" content=\"La DGT ha publicado la fecha del examen de director de autoescuela el 22 de noviembre de 2018 junto con el temario recomendado y los listados provisionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Examen de Directores de autoescuela: 22 de Noviembre de 2018\" \/>\n<meta property=\"og:description\" content=\"La DGT ha publicado la fecha del examen de director de autoescuela el 22 de noviembre de 2018 junto con el temario recomendado y los listados provisionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de la autoescuela\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-05T16:49:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-11T11:19:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00aa Carmen Alfonso Gal\u00e1n\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00aa Carmen Alfonso Gal\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/\",\"url\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/\",\"name\":\"Examen de Directores de autoescuela: 22 de Noviembre de 2018\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg\",\"datePublished\":\"2018-06-05T16:49:07+00:00\",\"dateModified\":\"2019-06-11T11:19:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e\"},\"description\":\"La DGT ha publicado la fecha del examen de director de autoescuela el 22 de noviembre de 2018 junto con el temario recomendado y los listados provisionales.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#primaryimage\",\"url\":\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg\",\"contentUrl\":\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg\",\"width\":400,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Examen de Directores de autoescuela: 22 de Noviembre de 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#website\",\"url\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/\",\"name\":\"Blog de la autoescuela\",\"description\":\"Noticias sobre autoescuelas y seguridad vial\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e\",\"name\":\"M\u00aa Carmen Alfonso Gal\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g\",\"caption\":\"M\u00aa Carmen Alfonso Gal\u00e1n\"},\"description\":\"Blog dedicado a la conducci\u00f3n, las autoescuelas y la seguridad vial. Est\u00e1 creado por un grupo de profesionales de la formaci\u00f3n vial que comparten inquietudes y experiencias. Aqu\u00ed\u00ad podr\u00e1s encontrar informaci\u00f3n variada sobre el d\u00ed\u00ada a d\u00ed\u00ada de la autoescuela, ex\u00e1menes, test o novedades y consejos para una conducci\u00f3n m\u00e1s segura.\",\"url\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/author\/carmen-a-g\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Examen de Directores de autoescuela: 22 de Noviembre de 2018","description":"La DGT ha publicado la fecha del examen de director de autoescuela el 22 de noviembre de 2018 junto con el temario recomendado y los listados provisionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/","og_locale":"es_ES","og_type":"article","og_title":"Examen de Directores de autoescuela: 22 de Noviembre de 2018","og_description":"La DGT ha publicado la fecha del examen de director de autoescuela el 22 de noviembre de 2018 junto con el temario recomendado y los listados provisionales.","og_url":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/","og_site_name":"Blog de la autoescuela","article_published_time":"2018-06-05T16:49:07+00:00","article_modified_time":"2019-06-11T11:19:04+00:00","og_image":[{"width":400,"height":200,"url":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg","type":"image\/jpeg"}],"author":"M\u00aa Carmen Alfonso Gal\u00e1n","twitter_misc":{"Escrito por":"M\u00aa Carmen Alfonso Gal\u00e1n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/","url":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/","name":"Examen de Directores de autoescuela: 22 de Noviembre de 2018","isPartOf":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg","datePublished":"2018-06-05T16:49:07+00:00","dateModified":"2019-06-11T11:19:04+00:00","author":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e"},"description":"La DGT ha publicado la fecha del examen de director de autoescuela el 22 de noviembre de 2018 junto con el temario recomendado y los listados provisionales.","breadcrumb":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#primaryimage","url":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg","contentUrl":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg","width":400,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/examen-de-directores-de-autoescuela-22-de-noviembre-de-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.blogdelaautoescuela.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Examen de Directores de autoescuela: 22 de Noviembre de 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#website","url":"https:\/\/www.blogdelaautoescuela.com\/blog\/","name":"Blog de la autoescuela","description":"Noticias sobre autoescuelas y seguridad vial","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogdelaautoescuela.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e","name":"M\u00aa Carmen Alfonso Gal\u00e1n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g","caption":"M\u00aa Carmen Alfonso Gal\u00e1n"},"description":"Blog dedicado a la conducci\u00f3n, las autoescuelas y la seguridad vial. Est\u00e1 creado por un grupo de profesionales de la formaci\u00f3n vial que comparten inquietudes y experiencias. Aqu\u00ed\u00ad podr\u00e1s encontrar informaci\u00f3n variada sobre el d\u00ed\u00ada a d\u00ed\u00ada de la autoescuela, ex\u00e1menes, test o novedades y consejos para una conducci\u00f3n m\u00e1s segura.","url":"https:\/\/www.blogdelaautoescuela.com\/blog\/author\/carmen-a-g\/"}]}},"jetpack_featured_media_url":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2009\/03\/autoescuelas1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p369yT-3HU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts\/14254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/comments?post=14254"}],"version-history":[{"count":6,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts\/14254\/revisions"}],"predecessor-version":[{"id":14260,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts\/14254\/revisions\/14260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/media\/779"}],"wp:attachment":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/media?parent=14254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/categories?post=14254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/tags?post=14254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}