
{"id":13364,"date":"2016-03-31T17:45:12","date_gmt":"2016-03-31T15:45:12","guid":{"rendered":"http:\/\/www.blogdelaautoescuela.com\/blog\/?p=13364"},"modified":"2019-05-09T11:50:46","modified_gmt":"2019-05-09T09:50:46","slug":"alergias-peligro-al-volante","status":"publish","type":"post","link":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/","title":{"rendered":"Alergias, un peligro al volante"},"content":{"rendered":"<p style=\"text-align: justify;\"><img data-opt-id=1632860005  fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13365\" src=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/http:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg\" alt=\"S\u00ed\u00adntomas alergia\" width=\"618\" height=\"527\" srcset=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:700\/h:597\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg 700w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:300\/h:256\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg 300w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:50\/h:43\/q:mauto\/f:best\/dpr:2\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg 50w\" sizes=\"(max-width: 475px) 100vw, 475px\" \/><\/p>\n<p style=\"text-align: justify;\">Las <strong>alergias\u00a0<\/strong>afectan hasta a un tercio de la poblaci\u00f3n de los pa\u00ed\u00adses occidentales y muchos de los antihistam\u00ed\u00adnicos tomados para tratarlas provocan somnolencia, peligrosa para la conducci\u00f3n. La <a href=\"http:\/\/revista.dgt.es\/es\/reportajes\/2016\/02FEBRERO\/0224-Alergias-2016.shtml#.Vv0zGuKLTIW\" target=\"_blank\" rel=\"noopener\">Direcci\u00f3n General de Tr\u00e1fico<\/a> ha lanzado una serie de consejos para aquellas personas que sufran alergia y vayan a conducir, as\u00ed\u00ad como una relaci\u00f3n de los medicamentos que provocan somnolencia y que son peligrosos si vamos a ponernos al volante.<\/p>\n<p style=\"text-align: justify;\">La alergia es una reacci\u00f3n de hipersensibilidad del sistema\u00a0inmunitario que identifica como nocivas determinadas sustancias inocuas \u20ac\u201cpor ejemplo, p\u00f3lenes de algunas plantas o \u00e1caros del polvo\u20ac\u201c habitualmente toleradas por la mayor\u00ed\u00ada de las personas. Las alergias m\u00e1s frecuentes son\u00a0la\u00a0rinitis al\u00e9rgica, que afecta al 25-30% de la poblaci\u00f3n de los pa\u00ed\u00adses desarrollados; el asma al\u00e9rgica, que afecta al 5% de la poblaci\u00f3n adulta; urticaria; dermatitis at\u00f3pica; dermatitis al\u00e9rgica de contacto y alergia alimentaria.<\/p>\n<p style=\"text-align: justify;\">La rinitis y el asma, la m\u00e1s comunes, provocan estornudos,\u00a0secreci\u00f3n nasal acuosa, picor de nariz y congesti\u00f3n nasal y suele coexistir con la conjuntivitis, que cursa con enrojecimiento, lagrimeo y picor ocular. Estas alergias afectan a la conducci\u00f3n segura ya que, por ejemplo, una serie de estornudos nos hace retirar la atenci\u00f3n de la conducci\u00f3n hasta 20 o 30 segundos. Por otro lado, los medicamentos que tomamos para tratar las alergias producen somnolencia.\u00a0El 40% de los pacientes que padecen rinitis al\u00e9rgica padecen somnolencia diurna, con las consecuencias negativas que esto implica sobre la conducci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><img data-opt-id=77714881  fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-13367\" src=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/http:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/efectos-antihistaminicos-conduccion.jpg\" alt=\"Efectos-antihist-2016\" width=\"585\" height=\"1580\" srcset=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:700\/h:1891\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/efectos-antihistaminicos-conduccion.jpg 700w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:111\/h:300\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/efectos-antihistaminicos-conduccion.jpg 111w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:379\/h:1024\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/efectos-antihistaminicos-conduccion.jpg 379w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:300\/h:810\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/efectos-antihistaminicos-conduccion.jpg 300w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:19\/h:50\/q:mauto\/f:best\/dpr:2\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/efectos-antihistaminicos-conduccion.jpg 19w\" sizes=\"(max-width: 475px) 100vw, 475px\" \/><\/p>\n<p style=\"text-align: justify;\">Consejos de la Direcci\u00f3n General de Tr\u00e1fico:<\/p>\n<p style=\"text-align: justify;\"><img data-opt-id=1000793964  data-opt-src=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/http:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/consejos-conductor-alergico.jpg\"  decoding=\"async\" class=\"aligncenter wp-image-13366\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"consejos-conductor-alergico\" width=\"577\" height=\"571\" old-srcset=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:650\/h:643\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/consejos-conductor-alergico.jpg 650w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:300\/h:297\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/consejos-conductor-alergico.jpg 300w, https:\/\/mlc4cka3cjnc.i.optimole.com\/w:50\/h:50\/q:mauto\/f:best\/dpr:2\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/consejos-conductor-alergico.jpg 50w\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las alergias\u00a0afectan hasta a un tercio de la poblaci\u00f3n de los pa\u00ed\u00adses occidentales y muchos de los antihistam\u00ed\u00adnicos tomados para tratarlas provocan somnolencia, peligrosa para la conducci\u00f3n. La Direcci\u00f3n General de Tr\u00e1fico ha lanzado una serie de consejos para aquellas personas que sufran alergia y vayan a conducir, as\u00ed\u00ad como una relaci\u00f3n de los medicamentos [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":13365,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":1,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[88,1730,477],"class_list":["post-13364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-vial","tag-alergias","tag-antihistaminicos","tag-direccion-general-de-trafico"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alergias, un peligro al volante | Blog de la autoescuela<\/title>\n<meta name=\"description\" content=\"Los antihistam\u00ed\u00adnicos tomados para tratar las alergias provocan somnolencia, peligrosa para la conducci\u00f3n. Consejos de la Direcci\u00f3n General de Tr\u00e1fico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alergias, un peligro al volante | Blog de la autoescuela\" \/>\n<meta property=\"og:description\" content=\"Los antihistam\u00ed\u00adnicos tomados para tratar las alergias provocan somnolencia, peligrosa para la conducci\u00f3n. Consejos de la Direcci\u00f3n General de Tr\u00e1fico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de la autoescuela\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-31T15:45:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-09T09:50:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"597\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00aa Carmen Alfonso Gal\u00e1n\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00aa Carmen Alfonso Gal\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/\",\"url\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/\",\"name\":\"Alergias, un peligro al volante | Blog de la autoescuela\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg\",\"datePublished\":\"2016-03-31T15:45:12+00:00\",\"dateModified\":\"2019-05-09T09:50:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e\"},\"description\":\"Los antihistam\u00ed\u00adnicos tomados para tratar las alergias provocan somnolencia, peligrosa para la conducci\u00f3n. Consejos de la Direcci\u00f3n General de Tr\u00e1fico.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#primaryimage\",\"url\":\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg\",\"contentUrl\":\"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg\",\"width\":700,\"height\":597,\"caption\":\"S\u00ed\u00adntomas alergias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alergias, un peligro al volante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#website\",\"url\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/\",\"name\":\"Blog de la autoescuela\",\"description\":\"Noticias sobre autoescuelas y seguridad vial\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e\",\"name\":\"M\u00aa Carmen Alfonso Gal\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g\",\"caption\":\"M\u00aa Carmen Alfonso Gal\u00e1n\"},\"description\":\"Blog dedicado a la conducci\u00f3n, las autoescuelas y la seguridad vial. Est\u00e1 creado por un grupo de profesionales de la formaci\u00f3n vial que comparten inquietudes y experiencias. Aqu\u00ed\u00ad podr\u00e1s encontrar informaci\u00f3n variada sobre el d\u00ed\u00ada a d\u00ed\u00ada de la autoescuela, ex\u00e1menes, test o novedades y consejos para una conducci\u00f3n m\u00e1s segura.\",\"url\":\"https:\/\/www.blogdelaautoescuela.com\/blog\/author\/carmen-a-g\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alergias, un peligro al volante | Blog de la autoescuela","description":"Los antihistam\u00ed\u00adnicos tomados para tratar las alergias provocan somnolencia, peligrosa para la conducci\u00f3n. Consejos de la Direcci\u00f3n General de Tr\u00e1fico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/","og_locale":"es_ES","og_type":"article","og_title":"Alergias, un peligro al volante | Blog de la autoescuela","og_description":"Los antihistam\u00ed\u00adnicos tomados para tratar las alergias provocan somnolencia, peligrosa para la conducci\u00f3n. Consejos de la Direcci\u00f3n General de Tr\u00e1fico.","og_url":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/","og_site_name":"Blog de la autoescuela","article_published_time":"2016-03-31T15:45:12+00:00","article_modified_time":"2019-05-09T09:50:46+00:00","og_image":[{"width":700,"height":597,"url":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg","type":"image\/jpeg"}],"author":"M\u00aa Carmen Alfonso Gal\u00e1n","twitter_misc":{"Escrito por":"M\u00aa Carmen Alfonso Gal\u00e1n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/","url":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/","name":"Alergias, un peligro al volante | Blog de la autoescuela","isPartOf":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#primaryimage"},"image":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#primaryimage"},"thumbnailUrl":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg","datePublished":"2016-03-31T15:45:12+00:00","dateModified":"2019-05-09T09:50:46+00:00","author":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e"},"description":"Los antihistam\u00ed\u00adnicos tomados para tratar las alergias provocan somnolencia, peligrosa para la conducci\u00f3n. Consejos de la Direcci\u00f3n General de Tr\u00e1fico.","breadcrumb":{"@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#primaryimage","url":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg","contentUrl":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg","width":700,"height":597,"caption":"S\u00ed\u00adntomas alergias"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/alergias-peligro-al-volante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.blogdelaautoescuela.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Alergias, un peligro al volante"}]},{"@type":"WebSite","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#website","url":"https:\/\/www.blogdelaautoescuela.com\/blog\/","name":"Blog de la autoescuela","description":"Noticias sobre autoescuelas y seguridad vial","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogdelaautoescuela.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/45ccd53611da46f9748652f0714d069e","name":"M\u00aa Carmen Alfonso Gal\u00e1n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.blogdelaautoescuela.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b413f0c79b29930663995c7dbb9ddc1?s=96&d=mm&r=g","caption":"M\u00aa Carmen Alfonso Gal\u00e1n"},"description":"Blog dedicado a la conducci\u00f3n, las autoescuelas y la seguridad vial. Est\u00e1 creado por un grupo de profesionales de la formaci\u00f3n vial que comparten inquietudes y experiencias. Aqu\u00ed\u00ad podr\u00e1s encontrar informaci\u00f3n variada sobre el d\u00ed\u00ada a d\u00ed\u00ada de la autoescuela, ex\u00e1menes, test o novedades y consejos para una conducci\u00f3n m\u00e1s segura.","url":"https:\/\/www.blogdelaautoescuela.com\/blog\/author\/carmen-a-g\/"}]}},"jetpack_featured_media_url":"https:\/\/mlc4cka3cjnc.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/www.blogdelaautoescuela.com\/blog\/wp-content\/uploads\/2016\/03\/Sintomas-alergia-700x.jpg","jetpack_shortlink":"https:\/\/wp.me\/p369yT-3ty","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts\/13364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/comments?post=13364"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts\/13364\/revisions"}],"predecessor-version":[{"id":14602,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/posts\/13364\/revisions\/14602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/media\/13365"}],"wp:attachment":[{"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/media?parent=13364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/categories?post=13364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdelaautoescuela.com\/blog\/wp-json\/wp\/v2\/tags?post=13364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}